{"id":383,"date":"2024-05-30T22:10:22","date_gmt":"2024-05-30T15:10:22","guid":{"rendered":"https:\/\/www.panasiachemical.co.th\/wps\/?page_id=383"},"modified":"2024-06-11T16:20:12","modified_gmt":"2024-06-11T09:20:12","slug":"products-simatec","status":"publish","type":"page","link":"https:\/\/www.panasiachemical.co.th\/wps\/products\/simatec\/","title":{"rendered":"Simatec"},"content":{"rendered":"<style>.kb-row-layout-id383_b7c2fd-4f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id383_b7c2fd-4f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id383_b7c2fd-4f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id383_b7c2fd-4f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id383_b7c2fd-4f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id383_b7c2fd-4f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id383_b7c2fd-4f alignwide wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column383_d287e5-5a > .kt-inside-inner-col,.kadence-column383_d287e5-5a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column383_d287e5-5a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column383_d287e5-5a > .kt-inside-inner-col{flex-direction:column;}.kadence-column383_d287e5-5a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column383_d287e5-5a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column383_d287e5-5a{position:relative;}@media all and (max-width: 1024px){.kadence-column383_d287e5-5a > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column383_d287e5-5a > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column383_d287e5-5a\"><div class=\"kt-inside-inner-col\"><style>.kb-image383_f1166b-87.kb-image-is-ratio-size, .kb-image383_f1166b-87 .kb-image-is-ratio-size{max-width:300px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image383_f1166b-87.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image383_f1166b-87 .kb-image-is-ratio-size{align-self:unset;}.kb-image383_f1166b-87{max-width:300px;}.image-is-svg.kb-image383_f1166b-87{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image383_f1166b-87 img{width:100%;}.kb-image383_f1166b-87 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image383_f1166b-87 size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"95\" src=\"https:\/\/www.panasiachemical.co.th\/wps\/wp-content\/uploads\/2024\/05\/simatec-300x95.png\" alt=\"\" class=\"kb-img wp-image-386\" srcset=\"https:\/\/www.panasiachemical.co.th\/wps\/wp-content\/uploads\/2024\/05\/simatec-300x95.png 300w, https:\/\/www.panasiachemical.co.th\/wps\/wp-content\/uploads\/2024\/05\/simatec.png 636w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n<style>.kb-row-layout-id383_49bc50-da > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id383_49bc50-da > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id383_49bc50-da > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1200px;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id383_49bc50-da > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id383_49bc50-da > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id383_49bc50-da > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id383_49bc50-da alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column383_740b56-00 > .kt-inside-inner-col,.kadence-column383_740b56-00 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column383_740b56-00 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column383_740b56-00 > .kt-inside-inner-col{flex-direction:column;}.kadence-column383_740b56-00 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column383_740b56-00 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column383_740b56-00{position:relative;}@media all and (max-width: 1024px){.kadence-column383_740b56-00 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column383_740b56-00 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column383_740b56-00\"><div class=\"kt-inside-inner-col\"><style>.kb-image383_ced4ea-07 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image383_ced4ea-07 size-large\"><a href=\"https:\/\/www.panasiachemical.co.th\/wps\/products\/simatec\/simalube\/\" class=\"kb-advanced-image-link\"><img decoding=\"async\" src=\"https:\/\/img1.wsimg.com\/isteam\/ip\/4f2dc32f-f6d8-45e5-91f1-890dbf466ee7\/simalube-Family.webp\/:\/cr=t:25%25,l:0%25,w:100%25,h:50%25\/rs=w:600,h:300,cg:true\" alt=\"\" class=\"kb-img\"\/><\/a><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading383_0e4c47-bb, .wp-block-kadence-advancedheading.kt-adv-heading383_0e4c47-bb[data-kb-block=\"kb-adv-heading383_0e4c47-bb\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading383_0e4c47-bb mark, .wp-block-kadence-advancedheading.kt-adv-heading383_0e4c47-bb[data-kb-block=\"kb-adv-heading383_0e4c47-bb\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading383_0e4c47-bb wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading383_0e4c47-bb\"><a href=\"https:\/\/www.panasiachemical.co.th\/wps\/products\/simatec\/simalube\/\">Simalube<\/a><\/h3>\n\n\n\n<p>Lubricating your assets with environmental&nbsp;<strong>&#8220;Hydrogen Gas Dry Cell&#8221;&nbsp;<\/strong>Technology<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column383_c62cfe-a3 > .kt-inside-inner-col,.kadence-column383_c62cfe-a3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column383_c62cfe-a3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column383_c62cfe-a3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column383_c62cfe-a3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column383_c62cfe-a3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column383_c62cfe-a3{position:relative;}@media all and (max-width: 1024px){.kadence-column383_c62cfe-a3 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column383_c62cfe-a3 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column383_c62cfe-a3\"><div class=\"kt-inside-inner-col\"><style>.kb-image383_2b4b66-61 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image383_2b4b66-61 size-large\"><a href=\"https:\/\/www.panasiachemical.co.th\/wps\/products\/simatec\/simatherm\/\" class=\"kb-advanced-image-link\"><img decoding=\"async\" src=\"https:\/\/img1.wsimg.com\/isteam\/ip\/4f2dc32f-f6d8-45e5-91f1-890dbf466ee7\/Volcano%20IH25.jpg\/:\/cr=t:15.75%25,l:0%25,w:100%25,h:68.5%25\/rs=w:474,h:237,cg:true\" alt=\"\" class=\"kb-img\"\/><\/a><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading383_f5d0ca-96, .wp-block-kadence-advancedheading.kt-adv-heading383_f5d0ca-96[data-kb-block=\"kb-adv-heading383_f5d0ca-96\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading383_f5d0ca-96 mark, .wp-block-kadence-advancedheading.kt-adv-heading383_f5d0ca-96[data-kb-block=\"kb-adv-heading383_f5d0ca-96\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading383_f5d0ca-96 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading383_f5d0ca-96\"><a href=\"https:\/\/www.panasiachemical.co.th\/wps\/products\/simatec\/simatherm\/\">Simatherm<\/a><\/h3>\n\n\n\n<p>Heating your component with<strong>&nbsp;&#8220;Induction Application&#8221;<\/strong><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column383_d0579f-43 > .kt-inside-inner-col,.kadence-column383_d0579f-43 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column383_d0579f-43 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column383_d0579f-43 > .kt-inside-inner-col{flex-direction:column;}.kadence-column383_d0579f-43 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column383_d0579f-43 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column383_d0579f-43{position:relative;}@media all and (max-width: 1024px){.kadence-column383_d0579f-43 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column383_d0579f-43 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column383_d0579f-43\"><div class=\"kt-inside-inner-col\"><style>.kb-image383_7440ae-1c .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image383_7440ae-1c size-large\"><a href=\"https:\/\/www.panasiachemical.co.th\/wps\/products\/simatec\/simatool\" class=\"kb-advanced-image-link\"><img decoding=\"async\" src=\"https:\/\/img1.wsimg.com\/isteam\/ip\/4f2dc32f-f6d8-45e5-91f1-890dbf466ee7\/simatool%20Family.jpg\/:\/cr=t:0%25,l:0%25,w:100%25,h:100%25\/rs=w:730,h:365,cg:true\" alt=\"\" class=\"kb-img\"\/><\/a><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading383_4de5f8-e9, .wp-block-kadence-advancedheading.kt-adv-heading383_4de5f8-e9[data-kb-block=\"kb-adv-heading383_4de5f8-e9\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading383_4de5f8-e9 mark, .wp-block-kadence-advancedheading.kt-adv-heading383_4de5f8-e9[data-kb-block=\"kb-adv-heading383_4de5f8-e9\"] mark{font-style:normal;color:#f76a0c;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading383_4de5f8-e9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading383_4de5f8-e9\"><a href=\"https:\/\/www.panasiachemical.co.th\/wps\/products\/simatec\/simatool\">Simatool<\/a><\/h3>\n\n\n\n<p>Professional and&nbsp;<strong>&#8220;Quality Tools&#8221;<\/strong>&nbsp;for assisting extraction and insertion<\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Simalube Lubricating your assets with environmental&nbsp;&#8220;Hydrogen Gas Dry Cell&#8221;&nbsp;Technology Simatherm Heating your component with&nbsp;&#8220;Induction Application&#8221; Simatool Professional and&nbsp;&#8220;Quality Tools&#8221;&nbsp;for assisting extraction and insertion<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":""},"class_list":["post-383","page","type-page","status-publish","hentry","description-off"],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"admin","author_link":"https:\/\/www.panasiachemical.co.th\/wps\/author\/chanchai_panasia\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/www.panasiachemical.co.th\/wps\/wp-json\/wp\/v2\/pages\/383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.panasiachemical.co.th\/wps\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.panasiachemical.co.th\/wps\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.panasiachemical.co.th\/wps\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.panasiachemical.co.th\/wps\/wp-json\/wp\/v2\/comments?post=383"}],"version-history":[{"count":3,"href":"https:\/\/www.panasiachemical.co.th\/wps\/wp-json\/wp\/v2\/pages\/383\/revisions"}],"predecessor-version":[{"id":523,"href":"https:\/\/www.panasiachemical.co.th\/wps\/wp-json\/wp\/v2\/pages\/383\/revisions\/523"}],"wp:attachment":[{"href":"https:\/\/www.panasiachemical.co.th\/wps\/wp-json\/wp\/v2\/media?parent=383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}